{"id":43620,"date":"2024-06-21T13:28:53","date_gmt":"2024-06-21T12:28:53","guid":{"rendered":"\/?p=43620"},"modified":"2024-08-24T13:30:41","modified_gmt":"2024-08-24T12:30:41","slug":"bizonyitvanyosztas-12-c","status":"publish","type":"post","link":"\/index.php\/2024\/06\/21\/bizonyitvanyosztas-12-c\/","title":{"rendered":"Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"43620\" class=\"elementor elementor-43620\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aad5d5c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aad5d5c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ab1f1c\" data-id=\"3ab1f1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df682e7 elementor-widget elementor-widget-spacer\" data-id=\"df682e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-229e884 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"229e884\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da28b24\" data-id=\"da28b24\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2b182f elementor-widget elementor-widget-text-editor\" data-id=\"a2b182f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><style id=\"bwg-style-0\">    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails {      width: 1254px;              justify-content: center;        margin:0 auto !important;              background-color: rgba(255, 255, 255, 0.00);            padding-left: 4px;      padding-top: 4px;      max-width: 100%;            }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item {    justify-content: flex-start;      max-width: 250px;          }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item a {       margin-right: 4px;       margin-bottom: 4px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item0 {      padding: 0px;            background-color:rgba(0,0,0, 0.30);      border: 0px none #CCCCCC;      opacity: 1.00;      border-radius: 0;      box-shadow: ;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {      max-height: none;      max-width: none;      padding: 0 !important;    }         @media only screen and (min-width: 480px) {\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img {\t\t\t-webkit-transition: all .3s; transition: all .3s;\t\t}\t\t#bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 img:hover {\t\t\t-ms-transform: scale(1.08);\t\t\t-webkit-transform: scale(1.08);\t\t\ttransform: scale(1.08);\t\t}\t\t\t\t.bwg-standard-thumbnails .bwg-zoom-effect .bwg-zoom-effect-overlay {\t\t\t\t\t\tbackground-color:rgba(0,0,0, 0.3);\t\t}\t\t.bwg-standard-thumbnails .bwg-zoom-effect:hover img {\t\t\t-ms-transform: scale(1.08);\t\t\t-webkit-transform: scale(1.08);\t\t\ttransform: scale(1.08);\t\t}\t\t      }\t    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-item1 {      padding-top: 56%;    }        #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-title1 {      position: absolute;      top: 0;      z-index: 100;      width: 100%;      height: 100%;      display: flex;      justify-content: center;      align-content: center;      flex-direction: column;      opacity: 0;    }\t      #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-title2,    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      color: #FFFFFF;      font-family: Ubuntu;      font-size: 16px;      font-weight: bold;      padding: 2px;      text-shadow: ;      max-height: 100%;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-thumb-description span {    color: #323A45;    font-family: Ubuntu;    font-size: 12px;    max-height: 100%;    word-wrap: break-word;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-play-icon2 {      font-size: 32px;    }    #bwg_container1_0 #bwg_container2_0 .bwg-container-0.bwg-standard-thumbnails .bwg-ecommerce2 {      font-size: 19.2px;      color: #323A45;    }    <\/style>    <div id=\"bwg_container1_0\"         class=\"bwg_container bwg_thumbnail bwg_thumbnails \"         data-right-click-protection=\"0\"         data-bwg=\"0\"         data-scroll=\"0\"         data-gallery-type=\"thumbnails\"         data-gallery-view-type=\"thumbnails\"         data-current-url=\"\/index.php\/wp-json\/wp\/v2\/posts\/43620\"         data-lightbox-url=\"\/wp-admin\/admin-ajax.php?action=GalleryBox&#038;current_view=0&#038;gallery_id=128&#038;tag=0&#038;theme_id=1&#038;shortcode_id=262&#038;sort_by=order&#038;order_by=asc&#038;current_url=%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F43620\"         data-gallery-id=\"128\"         data-popup-width=\"800\"         data-popup-height=\"500\"         data-is-album=\"gallery\"         data-buttons-position=\"bottom\">      <div id=\"bwg_container2_0\">             <div id=\"ajax_loading_0\" class=\"bwg_loading_div_1\">      <div class=\"bwg_loading_div_2\">        <div class=\"bwg_loading_div_3\">          <div id=\"loading_div_0\" class=\"bwg_spider_ajax_loading\">          <\/div>        <\/div>      <\/div>    <\/div>            <form id=\"gal_front_form_0\"              class=\"bwg-hidden\"              method=\"post\"              action=\"#\"              data-current=\"0\"              data-shortcode-id=\"262\"              data-gallery-type=\"thumbnails\"              data-gallery-id=\"128\"              data-tag=\"0\"              data-album-id=\"0\"              data-theme-id=\"1\"              data-ajax-url=\"\/wp-admin\/admin-ajax.php?action=bwg_frontend_data\">          <div id=\"bwg_container3_0\" class=\"bwg-background bwg-background-0\">                <div data-max-count=\"5\"         data-thumbnail-width=\"250\"         data-bwg=\"0\"         data-gallery-id=\"128\"         data-lightbox-url=\"\/wp-admin\/admin-ajax.php?action=GalleryBox&amp;current_view=0&amp;gallery_id=128&amp;tag=0&amp;theme_id=1&amp;shortcode_id=262&amp;sort_by=order&amp;order_by=asc&amp;current_url=%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fposts%2F43620\"         id=\"bwg_thumbnails_0\"         class=\"bwg-container-0 bwg-thumbnails bwg-standard-thumbnails bwg-container bwg-border-box\">            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4197\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_01.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4197\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_01.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_01.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_01\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_01\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_01<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4198\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_02.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4198\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_02.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_02.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_02\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_02\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_02<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4199\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_03.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4199\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_03.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_03.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_03\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_03\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_03<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4200\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_04.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4200\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_04.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_04.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_04\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_04\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_04<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4201\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_05.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4201\"                   data-width=\"334.00\"                   data-height=\"500.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_05.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_05.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_05\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_05\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_05<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4202\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_06.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4202\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_06.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_06.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_06\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_06\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_06<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4203\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_07.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4203\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_07.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_07.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_07\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_07\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_07<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4204\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_08.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4204\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_08.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_08.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_08\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_08\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_08<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4205\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_09.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4205\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_09.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_09.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_09\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_09\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_09<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4206\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_10.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4206\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_10.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_10.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_10\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_10\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_10<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4207\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_11.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4207\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_11.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_11.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_11\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_11\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_11<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4208\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_12.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4208\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_12.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_12.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_12\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_12\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_12<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4209\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_13.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4209\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_13.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_13.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_13\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_13\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_13<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4210\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_14.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4210\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_14.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_14.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_14\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_14\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_14<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4211\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_15.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4211\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_15.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_15.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_15\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_15\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_15<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4212\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_16.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4212\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_16.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_16.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_16\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_16\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_16<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4213\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_17.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4213\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_17.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_17.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_17\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_17\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_17<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4214\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_18.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4214\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_18.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_18.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_18\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_18\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_18<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4215\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_19.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4215\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_19.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_19.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_19\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_19\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_19<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4216\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_20.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4216\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_20.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_20.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_20\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_20\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_20<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4217\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_21.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4217\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_21.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_21.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_21\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_21\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_21<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4218\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_22.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4218\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_22.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_22.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_22\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_22\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_22<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4219\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_23.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4219\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_23.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_23.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_23\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_23\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_23<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4220\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_24.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4220\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_24.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_24.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_24\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_24\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_24<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4221\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_25.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4221\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_25.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_25.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_25\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_25\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_25<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4222\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_26.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4222\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_26.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_26.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_26\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_26\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_26<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4223\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_27.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4223\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_27.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_27.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_27\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_27\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_27<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4224\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_28.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4224\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_28.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_28.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_28\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_28\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_28<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4225\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_29.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4225\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_29.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_29.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_29\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_29\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_29<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>            <div class=\"bwg-item\">        <a class=\"bwg-a  bwg_lightbox\"  data-image-id=\"4226\" href=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/2024.06.21.-Bizonyitvanyosztas-12.C_30.jpg?bwg=1724502607\" data-elementor-open-lightbox=\"no\">                <div class=\"bwg-item0 \">          <div class=\"bwg-item1 bwg-zoom-effect\">            <div class=\"bwg-item2\">              <img decoding=\"async\" class=\"skip-lazy bwg_standart_thumb_img_0 \"                   data-id=\"4226\"                   data-width=\"500.00\"                   data-height=\"334.00\"                   data-src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_30.jpg?bwg=1724502607\"                   src=\"\/wp-content\/uploads\/photo-gallery\/imported_from_media_libray\/thumb\/2024.06.21.-Bizonyitvanyosztas-12.C_30.jpg?bwg=1724502607\"                   alt=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_30\"                   title=\"2024.06.21. - Bizony\u00edtv\u00e1nyoszt\u00e1s - 12.C_30\" \/>            <\/div>            <div class=\"bwg-zoom-effect-overlay\">              <div class=\"bwg-title1\"><div class=\"bwg-title2\">2024.06.21. &#8211; Bizony\u00edtv\u00e1nyoszt\u00e1s &#8211; 12.C_30<\/div><\/div>                                        <\/div>          <\/div>        <\/div>                        <\/a>              <\/div>          <\/div>    <style>      \/*pagination styles*\/      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 {\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin: 6px 0 4px;\t\t\t\tdisplay: block;      }      @media only screen and (max-width : 320px) {      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {     \t display: none;      }      }      #bwg_container1_0 #bwg_container2_0 .displaying-num_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tmargin-right: 10px;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .paging-input_0 {\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\tvertical-align: middle;      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:hover,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a.disabled:focus,\t\t\t#bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: default;\t\t\t\tcolor: rgba(102, 102, 102, 0.5);      }      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 a,      #bwg_container1_0 #bwg_container2_0 .tablenav-pages_0 input.bwg_current_page {\t\t\t\tcursor: pointer;\t\t\t\ttext-align: center;\t\t\t\tfont-size: 12px;\t\t\t\tfont-family: Ubuntu;\t\t\t\tfont-weight: bold;\t\t\t\tcolor: #666666;\t\t\t\ttext-decoration: none;\t\t\t\tpadding: 3px 6px;\t\t\t\tmargin: 0;\t\t\t\tborder-radius: 0;\t\t\t\tborder-style: solid;\t\t\t\tborder-width: 1px;\t\t\t\tborder-color: #E3E3E3;\t\t\t\t\t\t\t\tbackground-color: rgba(255, 255, 255, 1.00);\t\t\t\tbox-shadow: 0;\t\t\t\ttransition: all 0.3s ease 0s;-webkit-transition: all 0.3s ease 0s;      }      <\/style>      <span class=\"bwg_nav_cont_0\">              <div class=\"tablenav-pages_0\">                      <span class=\"pagination-links_0 pagination-links\" data-pages-count=\"2\">              <span class=\"pagination-links_col1\">              <a class=\"bwg-a first-page disabled\" title=\"Go to the first page\" >\u00ab<\/a>              <a class=\"bwg-a prev-page disabled\" title=\"Go to the previous page\" >\u2039<\/a>              <\/span>\t\t\t\t\t\t\t<span class=\"pagination-links_col2\">\t\t\t\t\t\t\t\t\t<input type=\"number\" class=\"bwg_current_page\" name=\"bwg_current_page\" value=\"1\" data-url-info=\"page_number_0\" onkeypress=\"return bwg_change_page_0(event, this)\" min=\"1\" oninput=\"validity.valid||(value='')\" \/>\t\t\t\t\t\t\t\t\t\tof\t\t\t\t\t\t\t\t\t\t<span class=\"total-pages_0\">\t\t\t\t\t\t\t\t\t\t\t2\t\t\t\t\t\t\t\t\t\t<\/span>\t\t\t\t\t\t\t<\/span>              <span class=\"pagination-links_col3\">                <a class=\"bwg-a next-page-0\" title=\"Go to the next page\" href=\"\/index.php\/wp-json\/wp\/v2\/posts\/43620?page_number_0=2\">\u203a<\/a>                <a class=\"bwg-a last-page-0\" title=\"Go to the last page\" href=\"\/index.php\/wp-json\/wp\/v2\/posts\/43620?page_number_0=2\">\u00bb<\/a>              <\/span>\t\t\t\t\t\t<\/span>\t\t\t\t\t\t        <\/div>                <input type=\"hidden\" id=\"page_number_0\" name=\"page_number_0\" value=\"1\" \/>      <script type=\"text\/javascript\">        if( jQuery('.bwg_nav_cont_0').length > 1 ) {          jQuery('.bwg_nav_cont_0').first().remove()        }        function spider_page_0(cur, x, y, load_more) {          if (typeof load_more == \"undefined\") {            var load_more = false;          }          if (jQuery(cur).hasClass('disabled')) {            return false;          }          var items_county_0 = 2;          switch (y) {            case 1:              if (x >= items_county_0) {                document.getElementById('page_number_0').value = items_county_0;              }              else {                document.getElementById('page_number_0').value = x + 1;              }              break;            case 2:              document.getElementById('page_number_0').value = items_county_0;              break;            case -1:              if (x == 1) {                document.getElementById('page_number_0').value = 1;              }              else {                document.getElementById('page_number_0').value = x - 1;              }              break;            case -2:              document.getElementById('page_number_0').value = 1;              break;\t\t\t\t\t\tcase 0:              document.getElementById('page_number_0').value = x;              break;            default:              document.getElementById('page_number_0').value = 1;          }          bwg_ajax('gal_front_form_0', '0', 'bwg_thumbnails_0', '0', '', 'gallery', 0, '', '', load_more, '', 1);        }                    jQuery('.first-page disabled').on('click', function () {              spider_page_0(this, 1, -2, 'numeric');              return false;            });            jQuery('.prev-page disabled').on('click', function () {              spider_page_0(this, 1, -1, 'numeric');              return false;            });            jQuery('.next-page-0').on('click', function () {              spider_page_0(this, 1, 1, 'numeric');              return false;            });            jQuery('.last-page-0').on('click', function () {              spider_page_0(this, 1, 2, 'numeric');              return false;            });        \t\t\t\t\/* Change page on input enter. *\/        function bwg_change_page_0( e, that ) {          if (  e.key == 'Enter' ) {            var to_page = parseInt(jQuery(that).val());            var pages_count = jQuery(that).parents(\".pagination-links\").data(\"pages-count\");            var current_url_param = jQuery(that).attr('data-url-info');            if (to_page > pages_count) {              to_page = 1;            }\t \t\t\t\t\t\t\t\t\t\t\t\tspider_page_0(this, to_page, 0, 'numeric');\t\t\t\t\t\t\treturn false;\t\t\t\t\t\t          }          return true;        }        jQuery('.bwg_load_btn_0').on('click', function () {            spider_page_0(this, 1, 1, true);            return false;        });      <\/script>      <\/span>                <\/div>        <\/form>        <style>          #bwg_container1_0 #bwg_container2_0 #spider_popup_overlay_0 {          background-color: #EEEEEE;          opacity: 0.60;          }          <\/style>        <div id=\"bwg_spider_popup_loading_0\" class=\"bwg_spider_popup_loading\"><\/div>        <div id=\"spider_popup_overlay_0\" class=\"spider_popup_overlay\" onclick=\"spider_destroypopup(1000)\"><\/div>        <input type=\"hidden\" id=\"bwg_random_seed_0\" value=\"1125860495\">                <\/div>    <\/div>    <script>      if (document.readyState === 'complete') {        if( typeof bwg_main_ready == 'function' ) {          if ( jQuery(\"#bwg_container1_0\").height() ) {            bwg_main_ready(jQuery(\"#bwg_container1_0\"));          }        }      } else {        document.addEventListener('DOMContentLoaded', function() {          if( typeof bwg_main_ready == 'function' ) {            if ( jQuery(\"#bwg_container1_0\").height() ) {             bwg_main_ready(jQuery(\"#bwg_container1_0\"));            }          }        });      }    <\/script>    \u00c9retts\u00e9gi t\u00f6rzslapkivonatot kaphattak k\u00e9zbe a 12\/C oszt\u00e1ly tanul\u00f3i. Igen, nem el\u00edr\u00e1s, nem \u00e9retts\u00e9gi bizony\u00edtv\u00e1nyt, hiszen \u0151k az els\u0151k, akik az \u00faj elj\u00e1r\u00e1srendben tehettek technikus tanul\u00f3kk\u00e9nt vizsg\u00e1t. E szerint az \u00f6t \u00e9ves technikusi k\u00e9pz\u00e9sben tanul\u00f3k az idei tan\u00e9vt\u0151l 12. oszt\u00e1ly \u00e9v v\u00e9g\u00e9n \u00e9retts\u00e9git tehetnek a k\u00f6zismereti t\u00e1rgyakb\u00f3l, azonban ahhoz, hogy az \u00e9retts\u00e9gi bizony\u00edtv\u00e1nyt is k\u00e9zhez kapj\u00e1k, szakmai t\u00e1rgyakb\u00f3l \u00e9s idegenyelvb\u0151l is meg kell szerezni a tan\u00fas\u00edtv\u00e1nyokat. Ez pedig csak 13. \u00e9v v\u00e9g\u00e9n lesz\u00a0 lehets\u00e9ges. A teljes a bizony\u00edtv\u00e1nyt az \u00e9retts\u00e9gr\u0151l csak akkor vehetik majd k\u00e9zbe. Term\u00e9szetesen ez is \u00f3ri\u00e1si munka volt, gratul\u00e1lunk minden k\u00f6zismereti tant\u00e1rgyb\u00f3l \u00e9retts\u00e9git megszerz\u0151 tanul\u00f3nknak! Szeptemberben tal\u00e1lkozunk, akkor m\u00e1r a v\u00e1lasztott szakm\u00e1kra koncentr\u00e1lhatnak a leend\u0151 cukr\u00e1sz szaktechnikusok \u00e9s turisztikai technikusok.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d8ffe0f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d8ffe0f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-071088f\" data-id=\"071088f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c9retts\u00e9gi t\u00f6rzslapkivonatot kaphattak k\u00e9zbe a 12\/C oszt\u00e1ly tanul\u00f3i. Igen, nem el\u00edr\u00e1s, nem \u00e9retts\u00e9gi bizony\u00edtv\u00e1nyt, hiszen \u0151k az els\u0151k, akik az \u00faj elj\u00e1r\u00e1srendben tehettek technikus tanul\u00f3kk\u00e9nt vizsg\u00e1t. E szerint az \u00f6t \u00e9ves technikusi k\u00e9pz\u00e9sben tanul\u00f3k az idei tan\u00e9vt\u0151l 12. oszt\u00e1ly \u00e9v v\u00e9g\u00e9n \u00e9retts\u00e9git tehetnek a k\u00f6zismereti t\u00e1rgyakb\u00f3l, azonban ahhoz, hogy az \u00e9retts\u00e9gi bizony\u00edtv\u00e1nyt is k\u00e9zhez kapj\u00e1k, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":43671,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-43620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vizsgak"],"_links":{"self":[{"href":"\/index.php\/wp-json\/wp\/v2\/posts\/43620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"\/index.php\/wp-json\/wp\/v2\/comments?post=43620"}],"version-history":[{"count":4,"href":"\/index.php\/wp-json\/wp\/v2\/posts\/43620\/revisions"}],"predecessor-version":[{"id":43670,"href":"\/index.php\/wp-json\/wp\/v2\/posts\/43620\/revisions\/43670"}],"wp:featuredmedia":[{"embeddable":true,"href":"\/index.php\/wp-json\/wp\/v2\/media\/43671"}],"wp:attachment":[{"href":"\/index.php\/wp-json\/wp\/v2\/media?parent=43620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"\/index.php\/wp-json\/wp\/v2\/categories?post=43620"},{"taxonomy":"post_tag","embeddable":true,"href":"\/index.php\/wp-json\/wp\/v2\/tags?post=43620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}